{"id":20780,"date":"2011-05-10T16:55:46","date_gmt":"2011-05-10T16:55:46","guid":{"rendered":"https:\/\/www.faronics.com\/?page_id=20780"},"modified":"2026-04-09T01:07:17","modified_gmt":"2026-04-09T08:07:17","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.faronics.com\/fr\/privacy-policy","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<p dir=\"ltr\"><span style=\"font-weight: 400;\"><b>Important<\/b><\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de soci\u00e9t\u00e9s d\u00e9sign\u00e9es ci-apr\u00e8s\u00a0:<br \/>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics Corporation<br \/>\n609 Granville St., Suite 1400<br \/>\nVancouver, BC V7Y 1G5<br \/>\nCanada<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics Technologies USA Inc.<br \/>\n5506 Sunol Blvd, Suite 202<br \/>\nPleasanton, CA 94566<br \/>\nUnited States of America<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics Pte. Ltd<br \/>\n6 Marina Boulevard<br \/>\n#36-22 The Sail at Marina Bay<br \/>\nSingapore, 018985<br \/>\nSingapore<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics Dubai<br \/>\nLiberty House,<br \/>\n4th Floor, Office 407, Al Sukook Street<br \/>\nZa&rsquo;abeel Second, DIFC, Dubai, United Arab Emirates<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics (EMEA) Ltd.<br \/>\n8 The Courtyard, Eastern Road,<br \/>\nBracknell, Berkshire,<br \/>\nRG12 2XB, United Kingdom<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics (EMEA) Ltd.<br \/>\n8 The Courtyard, Eastern Road,<br \/>\nBracknell, Berkshire,<br \/>\nRG12 2XB, United Kingdom<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">(le \u201c<\/span><b>Groupe\u00a0<\/b><span style=\"font-weight: 400;\">\u201d).<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Dans la pr\u00e9sente Politique de confidentialit\u00e9, les termes \u201c<\/span><b>Faronics<\/b><span style=\"font-weight: 400;\">\u201d, \u201c<\/span><b>nous\u00a0<\/b><span style=\"font-weight: 400;\">\u201d, \u201c<\/span><b>nos\u00a0<\/b><span style=\"font-weight: 400;\">\u201d ou \u201c<\/span><b>notre\u00a0<\/b><span style=\"font-weight: 400;\">\u201d, font r\u00e9f\u00e9rence \u00e0 la soci\u00e9t\u00e9 concern\u00e9e au sein du Groupe.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">La pr\u00e9sente Politique de confidentialit\u00e9 explique comment Faronics recueille, utilise et traite vos donn\u00e9es personnelles. <\/span><span style=\"font-weight: 400;\"> Elle fournit \u00e9galement certaines informations juridiquement obligatoires et, le cas \u00e9ch\u00e9ant, pr\u00e9sente vos droits en mati\u00e8re de donn\u00e9es personnelles.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous pouvons modifier notre Politique de confidentialit\u00e9 selon les besoins. Le cas \u00e9ch\u00e9ant, nous vous informerons de ces modifications au moyen d\u2019une notification publi\u00e9e sur notre site Web. Veuillez lire attentivement ce qui suit afin de comprendre nos positions et pratiques concernant vos informations personnelles et la fa\u00e7on dont nous les traitons.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Si vous avez des questions concernant la presente Politique de confidentialite ou le traitement de vos donnees personnelles, ou si vous souhaitez exercer vos droits en matiere de protection des donnees, vous pouvez contacter notre Delegue a la Protection des Donnees (DPD) a l&rsquo;adresse: dpo@faronics.com.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Donn\u00e9es personnelles<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Les informations personnelles ou donn\u00e9es personnelles d\u00e9signent les informations qui permettent en elles-m\u00eames d\u2019identifier une personne (comme son nom, son adresse, son num\u00e9ro de carte de cr\u00e9dit ou son adresse \u00e9lectronique) ainsi que les informations qui peuvent \u00eatre associ\u00e9es pour identifier une personne.<\/span><\/p>\n<h3 dir=\"ltr\"><span style=\"font-weight: 400;\">Moyens et sources de collecte des Donn\u00e9es personnelles<\/span><\/h3>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous recueillons les Donn\u00e9es personnelles aupr\u00e8s de personnes (y compris des repr\u00e9sentants agissant au nom de soci\u00e9t\u00e9s ou de personnes morales, comme les employ\u00e9s, dirigeants ou administrateurs) qui expriment un int\u00e9r\u00eat pour, s\u2019inscrivent pour, ou ach\u00e8tent nos produits en leur nom ou au nom de ces personnes morales, ou qui utilisent nos produits pour leur compte. \u00a0Ces personnes peuvent par ailleurs agir pour le compte de revendeurs ou de distributeurs agr\u00e9\u00e9s. Toutes ces personnes sont ici d\u00e9sign\u00e9es sous le terme de \u201c<\/span><b>Clients\u00a0<\/b><span style=\"font-weight: 400;\">\u201d). <\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics recueille les Donn\u00e9es personnelles de diverses fa\u00e7ons, notamment lorsqu\u2019une personne remplit un formulaire sur l\u2019un de nos sites Web, nous envoie un e-mail ou toute autre demande, participe \u00e0 un concours, publie un commentaire sur l\u2019un de nos forums communautaires, s\u2019inscrit pour, ach\u00e8te ou utilise un produit en son nom, ou s\u2019inscrit ou se connecte \u00e0 une section de nos sites Web ou de nos applications en ligne r\u00e9serv\u00e9e aux utilisateurs enregistr\u00e9s.<\/span><\/p>\n<h4 dir=\"ltr\"><span style=\"font-weight: 400;\">Utilisation de vos Donn\u00e9es personnelles et base l\u00e9gale<\/span><\/h4>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Le pr\u00e9sent chapitre explique en d\u00e9tail les finalit\u00e9s pour lesquelles nous traitons vos Donn\u00e9es personnelles, les cat\u00e9gories de Donn\u00e9es personnelles que nous traitons, et lorsque nous agissons en tant que \u00ab\u00a0contr\u00f4leur\u00a0\u00bb au sens du R\u00e8glement (UE) 2016\/679 (\u201c<\/span><b>Contr\u00f4leur europ\u00e9en\u00a0<\/b><span style=\"font-weight: 400;\">\u201d), les bases l\u00e9gales sur lesquelles nous nous appuyons pour traiter vos Donn\u00e9es personnelles.<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics utilise les noms, adresses, num\u00e9ros de t\u00e9l\u00e9phone, adresses \u00e9lectroniques (\u201c<\/span><b>Coordonn\u00e9es<\/b><span style=\"font-weight: 400;\">\u201d) et\/ou les num\u00e9ros de carte de cr\u00e9dit\/d\u00e9bit pour r\u00e9pondre aux demandes et commandes et les traiter. Lorsque nous agissons en tant que Contr\u00f4leur europ\u00e9en, la base l\u00e9gale de notre action est la n\u00e9cessit\u00e9 qu\u2019il existe pour nous \u00e0 poursuivre nos int\u00e9r\u00eats l\u00e9gitimes dans la prestation de services dans le cadre de nos op\u00e9rations commerciales. \u00a0\u00a0\u00a0 <\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics peut \u00e9galement utiliser vos Coordonn\u00e9es dans le but de vous envoyer des informations commerciales, notamment pour vous informer de nouvelles offres de produits. Pour cela, nous devons avoir obtenu votre consentement. \u00a0Si tel est le cas, nous pouvons \u00eatre amen\u00e9s \u00e0 vous contacter par t\u00e9l\u00e9phone ou par courrier postal ou \u00e9lectronique. Vous avez la possibilit\u00e9 de demander \u00e0 tout moment \u00e0 ne plus recevoir ce type de communication. Toutefois, ce choix ne concerne pas les demandes d\u2019assistance des produits que vous nous avez adress\u00e9es.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics peut \u00e9galement utiliser vos Coordonn\u00e9es dans le but de vous envoyer des informations commerciales, notamment pour vous informer de nouvelles offres de produits. Pour cela, nous devons avoir obtenu votre consentement. \u00a0Si tel est le cas, nous pouvons \u00eatre amen\u00e9s \u00e0 vous contacter par t\u00e9l\u00e9phone ou par courrier postal ou \u00e9lectronique. Vous avez la possibilit\u00e9 de demander \u00e0 tout moment \u00e0 ne plus recevoir ce type de communication. Toutefois, ce choix ne concerne pas les demandes d\u2019assistance des produits que vous nous avez adress\u00e9es.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous pouvons \u00e9galement utiliser vos Coordonn\u00e9es pour vous fournir des renseignements en rapport avec vos achats et pour administrer votre compte, lorsqu\u2019il y a lieu. Lorsque nous agissons en tant que Contr\u00f4leur europ\u00e9en, la base l\u00e9gale de notre action est la n\u00e9cessit\u00e9 qu\u2019il existe pour nous \u00e0 ex\u00e9cuter le contrat qui nous lie \u00e0 vous.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous pouvons utiliser vos Coordonn\u00e9es et faire valoir nos droits qui d\u00e9coulent de tout contrat conclu entre vous et nous, y compris \u00e0 des fins de facturation et de collecte. \u00a0Lorsque nous agissons en tant que Contr\u00f4leur europ\u00e9en, la base l\u00e9gale de notre action est la n\u00e9cessit\u00e9 qu\u2019il existe pour nous \u00e0 poursuivre nos int\u00e9r\u00eats l\u00e9gitimes \u00e0 faire valoir nos droits en vertu desdits contrats.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics peut \u00e9galement utiliser vos Coordonn\u00e9es pour vendre, pr\u00e9parer \u00e0 la vente ou disposer de notre activit\u00e9, en totalit\u00e9 ou en partie, y compris envers tout acheteur potentiel ou ses conseillers. \u00a0Lorsque nous agissons en tant que Contr\u00f4leur europ\u00e9en, la base l\u00e9gale de notre action est la n\u00e9cessit\u00e9 qu\u2019il existe pour nous \u00e0 poursuivre nos int\u00e9r\u00eats l\u00e9gitimes \u00e0 vendre ou disposer de notre activit\u00e9 ou de nos actifs.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Informations agr\u00e9g\u00e9es<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nos obtenons \u00e9galement et utilisons certaines donn\u00e9es agr\u00e9g\u00e9es comme des donn\u00e9es statistiques ou d\u00e9mographiques pour quelque usage que ce soit (\u201c<\/span><b>Informations agr\u00e9g\u00e9es\u00a0<\/b><span style=\"font-weight: 400;\">\u201d). Les Informations agr\u00e9g\u00e9es peuvent provenir de vos Donn\u00e9es personnelles, mais ne r\u00e9v\u00e8lent pas, directement ou indirectement, votre identit\u00e9 et ne sont pas des Donn\u00e9es personnelles. Nous pouvons utiliser les Informations agr\u00e9g\u00e9es pour am\u00e9liorer nos produits, en d\u00e9velopper de nouveaux, comprendre et\/ou analyser l\u2019utilisation, la demande et les tendances g\u00e9n\u00e9rales de l\u2019industrie, compiler et publier des livres blancs, des rapports et des bases de donn\u00e9es synth\u00e9tisant ce qui pr\u00e9c\u00e8de, et de fa\u00e7on g\u00e9n\u00e9rale, pour toute fin li\u00e9e \u00e0 notre activit\u00e9. \u00a0Nous pouvons \u00eatre amen\u00e9s \u00e0 communiquer les Informations agr\u00e9g\u00e9es \u00e0 des tiers. Les Informations agr\u00e9g\u00e9es peuvent provenir d\u2019informations fournies par un Client, de l\u2019utilisation de nos produits ou de techniques de collecte passive de donn\u00e9es d\u00e9crites ci-apr\u00e8s. La pr\u00e9sente Politique de confidentialit\u00e9 ne restreint ni ne limite notre collecte des Informations agr\u00e9g\u00e9es et l\u2019utilisation qui en est faite.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Services Cloud<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Les produits et services de Faronics simplifient la gestion informatique et sont con\u00e7us pour aider nos clients \u00e0 prot\u00e9ger la vie priv\u00e9e. Dans le cadre des Services Cloud, nous agissons en tant que <b>Sous-traitant (Processor)<\/b> et non en tant que <b>Responsable du traitement (Controller)<\/b> des informations envoy\u00e9es \u00e0 nos serveurs par les appareils g\u00e9r\u00e9s des clients. \u00c0 l\u2019aide de notre agent cloud, les appareils g\u00e9r\u00e9s de nos clients se connectent r\u00e9guli\u00e8rement \u00e0 notre console cloud s\u00e9curis\u00e9e et transmettent \u00e0 nos serveurs certaines informations concernant ces appareils (notamment l\u2019adresse IP, le nom de l\u2019appareil, le nom d\u2019utilisateur, la liste du mat\u00e9riel et des logiciels install\u00e9s). Lorsque c\u2019est n\u00e9cessaire, certains produits peuvent \u00e9galement recueillir des informations suppl\u00e9mentaires li\u00e9es aux actifs \u00e0 d\u2019autres fins : inventaire mat\u00e9riel\/logiciel, gestion des baux, migration de PC et conformit\u00e9 des licences logicielles.<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics traite les donn\u00e9es personnelles dans le cadre des Services Cloud fournis aux clients situ\u00e9s dans l\u2019EEE, au Royaume-Uni ou en Suisse conform\u00e9ment aux modalit\u00e9s de notre Addendum relatif au traitement des donn\u00e9es (DPA), lequel est int\u00e9gr\u00e9 par r\u00e9f\u00e9rence \u00e0 tout contrat de service : <a herf=\"https:\/\/www.faronics.com\/fr\/legal\/gdpr\">https:\/\/www.faronics.com\/fr\/legal\/gdpr<\/a><\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Lieu de stockage de vos Informations personnelles<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Les Donnees personnelles que nous recueillons aupr\u00e8s de vous  peuvent etre transferees et conservees dans une destination mondiale en dehors de l&rsquo;EEE, notamment au Canada, aux Etats-Unis, au Royaume-Uni, a Singapour, en Inde et a Dubai, ou operent les membres du groupe Faronics ou nos sous-traitants. Lorsque de tels transferts ont lieu, ils sont effectues conformement aux lois applicables en matiere de protection des donnees et sous reserve de garanties appropriees, notamment des mecanismes de transfert contractuels reconnus ou des mesures legales equivalentes s\u00fbre et conform\u00e9ment \u00e0 la pr\u00e9sente Politique de confidentialit\u00e9. \u00a0Les coordonn\u00e9es des membres du Groupe, notamment leur lieu d\u2019\u00e9tablissement, sont disponibles sous Locations (Sites) sur la page Contact Us (Nous contacter) du site Web du groupe\u00a0: <\/span><a href=\"https:\/\/www.faronics.com\/fr\/company_fr\/contact_fr\"><span style=\"font-weight: 400;\">https:\/\/www.faronics.com\/fr\/company_fr\/contact_fr<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Services aux Entreprises et Services Diriges par le Client<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Pour certains produits et services destines aux entreprises (ycompris les offres connectees au cloud fournies aux ecoles ou aux organisations), Faronics agit uniquement en tant que sous-traitant pour le compte du client. Dans ces cas, le client determine les finalites et les moyens du traitement des donnees personnelles et est responsable de fournir les avis de confidentialite requis aux utilisateurs finaux.<br \/>\nLorsque le traitement implique des transferts de donnees personnelles en dehors de l&rsquo;EEE, ces transferts sont effectues selon les instructions du client et sous reserve de garanties appropriees, notamment des Clauses Contractuelles Standard ou des mecanismes de transfert legaux equivalents. <\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Dur\u00e9e de conservation de vos Informations personnelles <\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous conservons vos Donn\u00e9es personnelles uniquement aussi longtemps que n\u00e9cessaire pour nous permettre de vous fournir nos produits et services et satisfaire aux exigences l\u00e9gales, qui dans certaines situations peuvent nous imposer de conserver certaines Donn\u00e9es personnelles pour une dur\u00e9e ind\u00e9termin\u00e9e. <\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Concernant les Donn\u00e9es personnelles que nous recueillons dans le cadre d\u2019une \u00e9valuation de nos produits et services, nous conservons les coordonn\u00e9es dans des syst\u00e8mes actifs pour une p\u00e9riode maximale d\u2019un\u00a0(1)\u00a0an apr\u00e8s la fin de l\u2019\u00e9valuation ou sur retrait du consentement. Ces donn\u00e9es peuvent demeurer dans des fichiers ou supports de sauvegarde jusqu\u2019\u00e0 un\u00a0(1)\u00a0an apr\u00e8s leur retrait.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">M\u00e9thodes de communication des Informations personnelles <\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics ne communique, vend, partage ou \u00e9change les Informations personnelles avec aucune partie ext\u00e9rieure au Groupe, sauf comme indiqu\u00e9 dans la pr\u00e9sente Politique de confidentialit\u00e9 ou avec le consentement appropri\u00e9. Nous pouvons divulguer des Informations personnelles \u00e0 un tiers dans les circonstances suivantes\u00a0:<br \/>\n<\/span><\/p>\n<ul>\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">pour ex\u00e9cuter nos Conditions d\u2019utilisation, politiques et autres relations contractuelles avec nos Clients\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">lorsque nous sommes convaincus en toute bonne foi que la divulgation est n\u00e9cessaire pour pr\u00e9venir la fraude ou y r\u00e9agir, pour d\u00e9fendre nos sites Web ou produits contre d\u2019\u00e9ventuelles attaques, ou pour prot\u00e9ger les biens et la s\u00e9curit\u00e9 de Faronics, de nos Clients ou du public\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">lorsque la loi l\u2019exige, par exemple pour se conformer \u00e0 une citation \u00e0 compara\u00eetre, un mandat, une surveillance r\u00e9glementaire ou une proc\u00e9dure judiciaire similaire\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">en lien avec toute vente, cession, fusion, consolidation ou autre transaction impliquant la totalit\u00e9 ou l\u2019int\u00e9gralit\u00e9 de notre soci\u00e9t\u00e9\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00e0 des conseillers professionnels externes, comme des comptables, des banquiers, des assureurs, des auditeurs et des avocats\u00a0;<br \/>\n<\/span><\/li>\n<\/ul>\n<ul style=\"padding-bottom: 20px;\">\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00e0 des entreprises qui proposent des services qui nous aident dans nos activit\u00e9s commerciales, comme le traitement des paiements des Clients. Ces entreprises sont autoris\u00e9es \u00e0 utiliser les Informations personnelles uniquement pour nous fournir ces services\u00a0; et<br \/>\n<\/span><\/li>\n<li dir=\"ltr\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">aux entreprises qui travaillent avec Faronics sur divers projets\u00a0; Faronics peut, par exemple, communiquer des Informations personnelles \u00e0 nos revendeurs partenaires afin d\u2019assurer la gestion de la relation client ou les op\u00e9rations marketing \u00e9lectroniques.<br \/>\n<\/span><\/li>\n<\/ul>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Transferts d\u2019Informations personnelles lorsque nous n\u2019agissons pas en tant que Contr\u00f4leur europ\u00e9en<br \/>\n<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Lorsque nous n\u2019agissons pas en tant que Contr\u00f4leur europ\u00e9en pour vos Donn\u00e9es personnelles, nous pouvons transf\u00e9rer ces derni\u00e8res vers d\u2019autres pays que celui dans lequel elles ont \u00e9t\u00e9 initialement recueillies. Il se peut que la l\u00e9gislation de ces pays en mati\u00e8re de protection de donn\u00e9es soit diff\u00e9rente de celle du pays dans lequel ces renseignements ont \u00e9t\u00e9 initialement fournis. Nous nous engageons \u00e0 prot\u00e9ger les Informations personnelles que nous transf\u00e9rons vers d\u2019autres pays, conform\u00e9ment \u00e0 la pr\u00e9sente Politique de confidentialit\u00e9.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Malheureusement, la transmission d\u2019informations via Internet n\u2019est pas enti\u00e8rement s\u00e9curis\u00e9e. Malgr\u00e9 tous nos efforts pour prot\u00e9ger vos Donn\u00e9es personnelles, nous ne pouvons garantir la s\u00e9curit\u00e9 de vos Donn\u00e9es personnelles transmises vers notre site\u00a0; toute transmission s\u2019effectue \u00e0 vos propres risques. Apr\u00e8s r\u00e9ception de vos Informations personnelles, nous appliquons des proc\u00e9dures et fonctions de s\u00e9curit\u00e9 strictes en vue d\u2019essayer de pr\u00e9venir tout acc\u00e8s non autoris\u00e9.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Cookies et autre collecte passive de donn\u00e9es<br \/>\n<\/span><\/h2>\n<h3 dir=\"ltr\"><span style=\"font-weight: 400;\">Cookies<\/span><\/h3>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Les cookies sont de petits fichiers texte plac\u00e9s sur votre appareil lorsque vous visitez des sites Web. Nous utilisons des cookies afin de vous reconna\u00eetre ainsi que vos pr\u00e9f\u00e9rences, d\u2019am\u00e9liorer les performances de nos sites Web et de recueillir des donn\u00e9es analytiques dans l\u2019int\u00e9r\u00eat de notre entreprise. Nos sites Web utilisent une combinaison de cookies de session (qui expirent avec votre session de navigation) et persistants (qui restent sur votre appareil apr\u00e8s l\u2019expiration de votre session de navigation) dans le but de nous permettre de vous proposer efficacement nos services et d\u2019am\u00e9liorer votre exp\u00e9rience d\u2019utilisation de nos sites Web. Les seuls cookies tiers que nous utilisons sont des cookies analytiques\/de performances, comme Google Analytics qui rassemblent des informations anonymis\u00e9es.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous utilisons les types de cookies suivants aux fins \u00e9nonc\u00e9es aux pr\u00e9sentes\u00a0:<br \/>\n<\/span><\/p>\n<h4 dir=\"ltr\"><span style=\"font-weight: 400;\">Cookies strictement n\u00e9cessaires<br \/>\n<\/span><\/h4>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Il s\u2019agit de cookies indispensables au bon fonctionnement de nos sites Web. Ce sont par exemple les cookies qui vous permettent de vous connecter aux espaces s\u00e9curis\u00e9s de nos sites Web, de placer des articles dans un panier ou de remplir un formulaire.<br \/>\n<\/span><\/p>\n<h4 dir=\"ltr\"><span style=\"font-weight: 400;\">Cookies analytiques\/de performances<br \/>\n<\/span><\/h4>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Ces cookies nous fournissent des informations statistiques sur nos sites Web que nous utilisons pour mesurer les performances et am\u00e9liorer le fonctionnement de nos sites Web. Ils nous permettent de vous reconna\u00eetre, de compter le nombre de visiteurs et de voir comment ceux-ci naviguent sur nos sites Web. Tous les renseignements recueillis par ces cookies sont agr\u00e9g\u00e9s et donc anonymes.<br \/>\n<\/span><\/p>\n<h4 dir=\"ltr\"><span style=\"font-weight: 400;\">Cookies de fonctionnalit\u00e9<br \/>\n<\/span><\/h4>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Ces cookies sont utilis\u00e9s pour vous reconna\u00eetre lorsque vous revenez sur un site Web. Ils nous permettent de personnaliser votre contenu, d\u2019adapter nos interactions avec vous et de m\u00e9moriser vos pr\u00e9f\u00e9rences.<br \/>\n<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">En continuant d\u2019utiliser nos sites Web, vous acceptez que nous placions ces types de cookies sur votre appareil. Vous pouvez bloquer la plupart des cookies en activant les param\u00e8tres de votre navigateur vous permettant de refuser tous les cookies ou seulement certains. Sachez toutefois que si vous choisissez de bloquer tous les cookies, vous ne serez peut-\u00eatre pas en mesure d\u2019acc\u00e9der \u00e0 certaines parties de nos sites Web. Si vous refusez que Google Analytics suive votre activit\u00e9 de navigation sur tous les sites Web, rendez-vous sur la page <\/span><a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">http:\/\/tools.google.com\/dlpage\/gaoptout<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3 dir=\"ltr\"><span style=\"font-weight: 400;\">Autre collecte passive de donn\u00e9es r\u00e9sultant de l\u2019utilisation de sites Web<br \/>\n<\/span><\/h3>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nous pouvons recueillir passivement des renseignements tels que des informations sur votre appareil, votre connexion, le type de navigateur utilis\u00e9, les sp\u00e9cificit\u00e9s d\u2019une requ\u00eate et votre adresse IP. \u00a0Nous rassemblons ces informations au moyen de diverses technologies comme les cookies (d\u00e9crits plus haut), les pixels espions (d\u00e9crits ci-apr\u00e8s) et d\u2019autres fichiers \u00e9lectroniques utilis\u00e9s pour suivre votre navigation sur nos sites Web, les transactions que vous effectuez et d\u2019autres comportements de navigation. \u00a0Faronics peut utiliser les pixels espions seuls ou avec des cookies en vue de faire fonctionner et d\u2019am\u00e9liorer nos sites Web, et de rassembler des informations sur l\u2019utilisation de nos sites Web et l\u2019interaction avec les e-mails et autres moyens de communication \u00e9lectronique de Faronics. Les pixels espions sont de petites images \u00e9lectroniques capables de reconna\u00eetre certains types d\u2019informations sur votre appareil, tels que les cookies, \u00e0 quel moment vous avez consult\u00e9 un site Web donn\u00e9 li\u00e9 \u00e0 un pixel espion et la description d\u2019un site Web li\u00e9 \u00e0 un pixel espion. Faronics peut placer des pixels espions dans ses e-mails marketing ou dans d\u2019autres messages \u00e9lectroniques, qui nous informent lorsque vous cliquez sur un lien contenu dans le message qui vous redirige vers l\u2019un de nos sites Web.<br \/>\n<\/span><\/p>\n<h3 dir=\"ltr\"><span style=\"font-weight: 400;\">Ne pas me suivre<br \/>\n<\/span><\/h3>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">En l\u2019absence de norme commune de l\u2019industrie ou de proc\u00e9dure visant \u00e0 interpr\u00e9ter les signaux Ne pas me suivre des navigateurs, Faronics ne r\u00e9pond actuellement pas \u00e0 ces signaux lors des interactions avec nos sites Web.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Liens externes\/sites Web tiers<br \/>\n<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Les sites Web de Faronics sont accessibles depuis des sites Web tiers et peuvent proposer des liens permettant d&rsquo;acc\u00e9der \u00e0 des sites Web tiers, notamment des sites de m\u00e9dias sociaux dont les politiques de confidentialit\u00e9 diff\u00e8rent de celles de Faronics. \u00a0M\u00eame si ce tiers est affili\u00e9 \u00e0 Faronics dans le cadre d\u2019un partenariat commercial ou autrement, Faronics n\u2019est pas responsable du contenu, des politiques de confidentialit\u00e9 ou des pratiques de ces sites Web tiers. Les liens externes sont fournis uniquement par commodit\u00e9. Vous y acc\u00e9dez \u00e0 vos propres risques. Nous vous encourageons \u00e0 lire attentivement la politique de confidentialit\u00e9 de tout site Web que vous pouvez consulter.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Enfants <\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Nos sites Web et produits ne sont pas con\u00e7us pour ou destin\u00e9s \u00e0 des mineurs, et nous ne cherchons pas sciemment \u00e0 solliciter ou \u00e0 recevoir des informations d\u2019enfants. Toutefois, si un enfant \u00e2g\u00e9 de moins de 13\u00a0ans a communiqu\u00e9 \u00e0 Faronics des Informations personnelles, .le parent ou le tuteur doit contacter Faronics immediatement a l&rsquo;adresse: <\/span><a href=\"mailto:dpo@faronics.com\"><span style=\"font-weight: 400;\">dpo@faronics.com<\/span><\/a><span style=\"font-weight: 400;\"> afin de nous permettre de supprimer ces informations de nos fichiers.<br \/>\n<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Vos droits \u2014 Declaration RGPD sur la prise de decision automatisee <\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Faronics n&rsquo;effectue pas de prise de decision automatisee ni de profilage au sens de l&rsquo;article 22 du RGPD.<\/span><\/p>\n<h2 dir=\"ltr\"><span style=\"font-weight: 400;\">Vos droits<br \/>\n<\/span><\/h2>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Vous avez le droit de nous demander de ne pas traiter vos Donn\u00e9es personnelles \u00e0 des fins marketing. <\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Lorsque nous agissons en tant que Contr\u00f4leur europ\u00e9en de vos Donn\u00e9es personnelles, vous pouvez disposer d\u2019un certain nombre de droits associ\u00e9s au traitement de vos Donn\u00e9es personnelles, notamment\u00a0:<br \/>\n<\/span><\/p>\n<ul>\n<li dir=\"ltr\"><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">le droit de demander l\u2019acc\u00e8s \u00e0 vos Donn\u00e9es personnelles que nous traitons ou contr\u00f4lons\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\"><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">le droit de demander la rectification des inexactitudes contenues dans vos Donn\u00e9es personnelles ou, selon la finalit\u00e9 du traitement, de demander \u00e0 ce que les informations incompl\u00e8tes soient compl\u00e9t\u00e9es\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\"><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">le droit de demander, pour des motifs l\u00e9gitimes d\u00e9finis par la loi\u00a0:<br \/>\n<\/span><\/li>\n<\/ul>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">(a)<\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">erasure of your personal data that we process or control ; or<\/span><\/p>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">(b)<\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">la restriction du traitement de vos Donn\u00e9es personnelles que nous traitons ou contr\u00f4lons\u00a0;<br \/>\n<\/span><\/p>\n<ul>\n<li dir=\"ltr\"><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">le droit de vous opposer, pour des motifs l\u00e9gitimes d\u00e9finis par la loi, au traitement de vos Donn\u00e9es personnelles\u00a0;<br \/>\n<\/span><\/li>\n<li dir=\"ltr\"><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">le droit de recevoir vos Donn\u00e9es personnelles dans un format structur\u00e9, commun\u00e9ment utilis\u00e9 et lisible par une machine, et de demander le transfert de vos donn\u00e9es \u00e0 un autre contr\u00f4leur, dans la mesure permise par la loi en vigueur\u00a0; et<br \/>\n<\/span><\/li>\n<li dir=\"ltr\"><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\"><span> <\/span><\/span><span style=\"font-weight: 400;\">le droit de porter plainte concernant le traitement de vos Donn\u00e9es personnelles aupr\u00e8s du Commissariat \u00e0 l\u2019information ou d\u2019une autre instance de surveillance comp\u00e9tente. Des informations relatives \u00e0 la proc\u00e9dure \u00e0 suivre sont disponibles sur la page https:\/\/ico.org.uk\/concerns\/<\/span><\/li>\n<\/ul>\n<p dir=\"ltr\"><span style=\"font-weight: 400;\">Si vous souhaitez exercer l\u2019un ou l\u2019autre des droits \u00e9nonc\u00e9s pr\u00e9c\u00e9demment, veuillez utiliser les coordonn\u00e9es communiqu\u00e9es dans le premier chapitre de la pr\u00e9sente Politique de confidentialit\u00e9 pour nous contacter.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p dir=\"ltr\">Important<\/p>\n<p dir=\"ltr\">Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de soci\u00e9t\u00e9s d\u00e9sign\u00e9es ci-apr\u00e8s\u00a0: <\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Faronics Corporation 609 Granville St., Suite 1400 Vancouver, BC V7Y 1G5 Canada<\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Faronics Technologies USA Inc. 5506 Sunol Blvd, Suite 202 Pleasanton, CA 94566 United States of America<\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Faronics Pte. Ltd 6 Marina Boulevard #36-22 The Sail at Marina Bay Singapore, 018985 Singapore<\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Faronics Dubai Liberty House, 4th Floor, Office 407, Al Sukook Street Za&rsquo;abeel Second, DIFC, Dubai, United Arab Emirates<\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Faronics (EMEA) Ltd. 8 The Courtyard, Eastern Road, Bracknell, Berkshire, RG12 2XB, United Kingdom<\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Faronics (EMEA) Ltd. 8 The Courtyard, Eastern Road, Bracknell, Berkshire, RG12 2XB, United Kingdom<\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">(le \u201cGroupe\u00a0\u201d).<\/p>\n<p dir=\"ltr\">Dans la pr\u00e9sente Politique de confidentialit\u00e9, les termes \u201cFaronics\u201d, \u201cnous\u00a0\u201d, \u201cnos\u00a0\u201d ou \u201cnotre\u00a0\u201d, font r\u00e9f\u00e9rence \u00e0 la soci\u00e9t\u00e9 concern\u00e9e au sein du Groupe. <\/p>\n<p dir=\"ltr\">La pr\u00e9sente Politique de confidentialit\u00e9 explique comment Faronics recueille, utilise et traite vos donn\u00e9es personnelles. Elle fournit \u00e9galement certaines informations juridiquement obligatoires et, le cas \u00e9ch\u00e9ant, pr\u00e9sente vos droits en mati\u00e8re de donn\u00e9es personnelles. <\/p>\n<p dir=\"ltr\">Nous pouvons modifier notre Politique de confidentialit\u00e9 selon les besoins. Le cas \u00e9ch\u00e9ant, nous vous informerons de ces modifications au moyen d\u2019une notification publi\u00e9e sur notre site Web. Veuillez lire attentivement ce qui suit afin de comprendre nos positions et pratiques concernant vos informations personnelles et la fa\u00e7on dont nous les traitons. <\/p>\n<div class=\"more\"><a href=\"https:\/\/www.faronics.com\/fr\/privacy-policy\">Continue Reading&#8230;<\/a><\/div>\n","protected":false},"author":116,"featured_media":0,"parent":0,"menu_order":99,"comment_status":"open","ping_status":"closed","template":"page-template-with-sidebar.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-20780","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Privacy Policy - Faronics<\/title>\n<meta name=\"description\" content=\"Important Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.faronics.com\/fr\/privacy-policy\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy\" \/>\n<meta property=\"og:description\" content=\"Important Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.faronics.com\/fr\/privacy-policy\" \/>\n<meta property=\"og:site_name\" content=\"Faronics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/faronics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T08:07:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@faronics\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr\\\/privacy-policy\",\"url\":\"https:\\\/\\\/www.faronics.com\\\/fr\\\/privacy-policy\",\"name\":\"Privacy Policy - Faronics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr#website\"},\"datePublished\":\"2011-05-10T16:55:46+00:00\",\"dateModified\":\"2026-04-09T08:07:17+00:00\",\"description\":\"Important Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr\\\/privacy-policy#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.faronics.com\\\/fr\\\/privacy-policy\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr\\\/privacy-policy#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.faronics.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\",\"item\":\"https:\\\/\\\/www.faronics.com\\\/fr\\\/privacy-policy\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr#website\",\"url\":\"https:\\\/\\\/www.faronics.com\\\/fr\",\"name\":\"Faronics\",\"description\":\"Cr\u00e9ateurs de Deep Freeze et d'autres solutions de s\u00e9curit\u00e9 multicouche\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.faronics.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr#organization\",\"name\":\"Faronics\",\"url\":\"https:\\\/\\\/www.faronics.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.faronics.com\\\/assets\\\/footer-faronics-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.faronics.com\\\/assets\\\/footer-faronics-logo.png\",\"width\":155,\"height\":44,\"caption\":\"Faronics\"},\"image\":{\"@id\":\"https:\\\/\\\/www.faronics.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/faronics\",\"https:\\\/\\\/x.com\\\/faronics\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Privacy Policy - Faronics","description":"Important Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.faronics.com\/fr\/privacy-policy","og_locale":"fr_FR","og_type":"article","og_title":"Privacy Policy","og_description":"Important Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de","og_url":"https:\/\/www.faronics.com\/fr\/privacy-policy","og_site_name":"Faronics","article_publisher":"https:\/\/www.facebook.com\/faronics","article_modified_time":"2026-04-09T08:07:17+00:00","twitter_card":"summary_large_image","twitter_site":"@faronics","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.faronics.com\/fr\/privacy-policy","url":"https:\/\/www.faronics.com\/fr\/privacy-policy","name":"Privacy Policy - Faronics","isPartOf":{"@id":"https:\/\/www.faronics.com\/fr#website"},"datePublished":"2011-05-10T16:55:46+00:00","dateModified":"2026-04-09T08:07:17+00:00","description":"Important Le pr\u00e9sent document constitue la Politique de confidentialit\u00e9 de Faronics Corporation et Faronics Pte Ltd. et des autres membres de ce groupe de","breadcrumb":{"@id":"https:\/\/www.faronics.com\/fr\/privacy-policy#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.faronics.com\/fr\/privacy-policy"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.faronics.com\/fr\/privacy-policy#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.faronics.com\/fr"},{"@type":"ListItem","position":2,"name":"Privacy Policy","item":"https:\/\/www.faronics.com\/fr\/privacy-policy\/"}]},{"@type":"WebSite","@id":"https:\/\/www.faronics.com\/fr#website","url":"https:\/\/www.faronics.com\/fr","name":"Faronics","description":"Cr\u00e9ateurs de Deep Freeze et d'autres solutions de s\u00e9curit\u00e9 multicouche","publisher":{"@id":"https:\/\/www.faronics.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.faronics.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.faronics.com\/fr#organization","name":"Faronics","url":"https:\/\/www.faronics.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.faronics.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/www.faronics.com\/assets\/footer-faronics-logo.png","contentUrl":"https:\/\/www.faronics.com\/assets\/footer-faronics-logo.png","width":155,"height":44,"caption":"Faronics"},"image":{"@id":"https:\/\/www.faronics.com\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/faronics","https:\/\/x.com\/faronics"]}]}},"_links":{"self":[{"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/pages\/20780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/comments?post=20780"}],"version-history":[{"count":4,"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/pages\/20780\/revisions"}],"predecessor-version":[{"id":276490,"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/pages\/20780\/revisions\/276490"}],"wp:attachment":[{"href":"https:\/\/www.faronics.com\/fr\/wp-json\/wp\/v2\/media?parent=20780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}